{"id":6125,"date":"2022-08-25T12:19:06","date_gmt":"2022-08-25T16:19:06","guid":{"rendered":"https:\/\/www2.law.temple.edu\/voices\/?p=6125"},"modified":"2022-10-13T12:26:15","modified_gmt":"2022-10-13T16:26:15","slug":"trumps-legal-troubles-2","status":"publish","type":"post","link":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/","title":{"rendered":"Trump&#8217;s legal troubles"},"content":{"rendered":"<p>Prof. Lauren Ouziel joins former NSA lawyer Glenn Gerstell and Guardian congressional reporter Hugo Lowell in a conversation about former President Trump&#8217;s growing legal trouble on Radio Times.<\/p>\n<p><a href=\"https:\/\/whyy.org\/episodes\/trumps-legal-troubles\/\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prof. Lauren Ouziel joins former NSA lawyer Glenn Gerstell and Guardian congressional reporter Hugo Lowell in a conversation about former President Trump&#8217;s growing legal trouble on Radio Times. Read More<\/p>\n","protected":false},"author":20,"featured_media":6126,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"audience":[],"coauthors":[42,1052],"class_list":["post-6125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faculty-in-the-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Trump&#039;s legal troubles - Voices at Temple<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Trump&#039;s legal troubles - Voices at Temple\" \/>\r\n<meta property=\"og:description\" content=\"Prof. Lauren Ouziel joins former NSA lawyer Glenn Gerstell and Guardian congressional reporter Hugo Lowell in a conversation about former President Trump&#8217;s growing legal trouble on Radio Times. Read More\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Voices at Temple\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-08-25T16:19:06+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-10-13T16:26:15+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"840\" \/>\r\n\t<meta property=\"og:image:height\" content=\"560\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Lauren Ouziel, Nicole Regis\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauren Ouziel, Nicole Regis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/\"},\"author\":{\"name\":\"Nicole Regis\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/#\\\/schema\\\/person\\\/40cdedd867c98fae0cb57440de866aa1\"},\"headline\":\"Trump&#8217;s legal troubles\",\"datePublished\":\"2022-08-25T16:19:06+00:00\",\"dateModified\":\"2022-10-13T16:26:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg\",\"articleSection\":[\"Faculty in the Media\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/\",\"url\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/\",\"name\":\"Trump's legal troubles - Voices at Temple\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg\",\"datePublished\":\"2022-08-25T16:19:06+00:00\",\"dateModified\":\"2022-10-13T16:26:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/#\\\/schema\\\/person\\\/40cdedd867c98fae0cb57440de866aa1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg\",\"contentUrl\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg\",\"width\":840,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/trumps-legal-troubles-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump&#8217;s legal troubles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/#website\",\"url\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/\",\"name\":\"Voices at Temple\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/#\\\/schema\\\/person\\\/40cdedd867c98fae0cb57440de866aa1\",\"name\":\"Nicole Regis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g933344a1555d061467bf04a72c1b5484\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g\",\"caption\":\"Nicole Regis\"},\"url\":\"https:\\\/\\\/www2.law.temple.edu\\\/voices\\\/author\\\/tug13741\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump's legal troubles - Voices at Temple","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/","og_locale":"en_US","og_type":"article","og_title":"Trump's legal troubles - Voices at Temple","og_description":"Prof. Lauren Ouziel joins former NSA lawyer Glenn Gerstell and Guardian congressional reporter Hugo Lowell in a conversation about former President Trump&#8217;s growing legal trouble on Radio Times. Read More","og_url":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/","og_site_name":"Voices at Temple","article_published_time":"2022-08-25T16:19:06+00:00","article_modified_time":"2022-10-13T16:26:15+00:00","og_image":[{"width":840,"height":560,"url":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","type":"image\/jpeg"}],"author":"Lauren Ouziel, Nicole Regis","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lauren Ouziel, Nicole Regis","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#article","isPartOf":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/"},"author":{"name":"Nicole Regis","@id":"https:\/\/www2.law.temple.edu\/voices\/#\/schema\/person\/40cdedd867c98fae0cb57440de866aa1"},"headline":"Trump&#8217;s legal troubles","datePublished":"2022-08-25T16:19:06+00:00","dateModified":"2022-10-13T16:26:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/"},"wordCount":33,"image":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","articleSection":["Faculty in the Media"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/","url":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/","name":"Trump's legal troubles - Voices at Temple","isPartOf":{"@id":"https:\/\/www2.law.temple.edu\/voices\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#primaryimage"},"image":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","datePublished":"2022-08-25T16:19:06+00:00","dateModified":"2022-10-13T16:26:15+00:00","author":{"@id":"https:\/\/www2.law.temple.edu\/voices\/#\/schema\/person\/40cdedd867c98fae0cb57440de866aa1"},"breadcrumb":{"@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#primaryimage","url":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","contentUrl":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","width":840,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/www2.law.temple.edu\/voices\/trumps-legal-troubles-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www2.law.temple.edu\/voices\/"},{"@type":"ListItem","position":2,"name":"Trump&#8217;s legal troubles"}]},{"@type":"WebSite","@id":"https:\/\/www2.law.temple.edu\/voices\/#website","url":"https:\/\/www2.law.temple.edu\/voices\/","name":"Voices at Temple","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www2.law.temple.edu\/voices\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www2.law.temple.edu\/voices\/#\/schema\/person\/40cdedd867c98fae0cb57440de866aa1","name":"Nicole Regis","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g933344a1555d061467bf04a72c1b5484","url":"https:\/\/secure.gravatar.com\/avatar\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a704cd7da01b46fedfebff14050ad68ae3d0d990fc0f126c3939cf591b986bb2?s=96&d=mm&r=g","caption":"Nicole Regis"},"url":"https:\/\/www2.law.temple.edu\/voices\/author\/tug13741\/"}]}},"jetpack_featured_media_url":"https:\/\/www2.law.temple.edu\/voices\/cms\/wp-content\/uploads\/2022\/10\/2022.08.18_LaurenOuziel_WHYY_Voices.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/posts\/6125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/comments?post=6125"}],"version-history":[{"count":1,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/posts\/6125\/revisions"}],"predecessor-version":[{"id":6127,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/posts\/6125\/revisions\/6127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/media\/6126"}],"wp:attachment":[{"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/media?parent=6125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/categories?post=6125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/tags?post=6125"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/audience?post=6125"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.law.temple.edu\/voices\/wp-json\/wp\/v2\/coauthors?post=6125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}